{"id":887,"date":"2023-08-24T16:50:49","date_gmt":"2023-08-24T14:50:49","guid":{"rendered":"https:\/\/askal.lu\/recuperation-de-leau-de-pluie\/"},"modified":"2025-12-08T12:18:16","modified_gmt":"2025-12-08T11:18:16","slug":"recuperation-de-leau-de-pluie","status":"publish","type":"page","link":"https:\/\/askal.lu\/fr\/recuperation-de-leau-de-pluie\/","title":{"rendered":"R\u00e9cup\u00e9ration de l&rsquo;eau de pluie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"887\" class=\"elementor elementor-887 elementor-465\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2986fdf elementor-section-height-min-height elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"2986fdf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:471,&quot;url&quot;:&quot;https:\\\/\\\/askal.lu\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Regen.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78cb2b1\" data-id=\"78cb2b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c730a12\" data-id=\"c730a12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c063daf elementor-widget elementor-widget-heading\" data-id=\"c063daf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cadeau de la nature<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbe381f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbe381f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14fc3e5\" data-id=\"14fc3e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7311bd1 elementor-widget elementor-widget-heading\" data-id=\"7311bd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">R\u00e9cup\u00e9ration de l'eau de pluie<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b31a760 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b31a760\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-db453c3\" data-id=\"db453c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e37fa91 elementor-widget elementor-widget-image\" data-id=\"e37fa91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/askal.lu\/wp-content\/uploads\/2023\/08\/man-3581659_1920.jpeg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-468\" alt=\"regen pluie\" srcset=\"https:\/\/askal.lu\/wp-content\/uploads\/2023\/08\/man-3581659_1920.jpeg 1920w, https:\/\/askal.lu\/wp-content\/uploads\/2023\/08\/man-3581659_1920-300x200.jpeg 300w, https:\/\/askal.lu\/wp-content\/uploads\/2023\/08\/man-3581659_1920-1024x683.jpeg 1024w, https:\/\/askal.lu\/wp-content\/uploads\/2023\/08\/man-3581659_1920-768x512.jpeg 768w, https:\/\/askal.lu\/wp-content\/uploads\/2023\/08\/man-3581659_1920-1536x1024.jpeg 1536w, https:\/\/askal.lu\/wp-content\/uploads\/2023\/08\/man-3581659_1920-930x620.jpeg 930w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-818b8a6\" data-id=\"818b8a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-885567b elementor-widget elementor-widget-text-editor\" data-id=\"885567b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #95c03b;\">R\u00e9cup\u00e9ration de l&rsquo;eau de pluie : utilisez la force de la pluie pour votre m\u00e9nage !<\/span><\/h4>\n<p>L&rsquo;eau de pluie est une ressource pr\u00e9cieuse qui est souvent sous-estim\u00e9e. Une installation de r\u00e9cup\u00e9ration d&rsquo;eau de pluie vous permet d&rsquo;utiliser ce bien pr\u00e9cieux \u00e0 bon escient et de r\u00e9duire votre consommation d&rsquo;eau. Pour ce faire, l&rsquo;eau de pluie collect\u00e9e sur votre toit est r\u00e9cup\u00e9r\u00e9e, stock\u00e9e et r\u00e9utilis\u00e9e \u00e0 diff\u00e9rentes fins dans votre foyer. Il s&rsquo;agit d&rsquo;une solution durable qui permet \u00e0 la fois de prot\u00e9ger l&rsquo;environnement et de r\u00e9duire votre facture d&rsquo;eau.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7580827 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7580827\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-376f090\" data-id=\"376f090\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1619b6a elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"1619b6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-water\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d896d14 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d896d14\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ac6eee4\" data-id=\"ac6eee4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27cffe0 elementor-widget elementor-widget-text-editor\" data-id=\"27cffe0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #95c03b;\">Pourquoi utiliser l&rsquo;eau de pluie ?<\/span><\/h4>\n<p>Il existe de nombreuses bonnes raisons d&rsquo;opter pour la r\u00e9cup\u00e9ration de l&rsquo;eau de pluie :<\/p>\n<ol>\n<li><strong>\u00c9conomies d&rsquo;eau et de co\u00fbts :<\/strong> En utilisant l&rsquo;eau de pluie pour la chasse d&rsquo;eau, l&rsquo;arrosage du jardin ou la machine \u00e0 laver, vous pouvez r\u00e9duire consid\u00e9rablement votre consommation d&rsquo;eau potable et ainsi \u00e9conomiser de l&rsquo;argent.<\/li>\n<li><strong>Durabilit\u00e9 :<\/strong> la r\u00e9cup\u00e9ration de l&rsquo;eau de pluie contribue \u00e0 pr\u00e9server les ressources en eau potable et \u00e0 r\u00e9duire la pression sur le syst\u00e8me public d&rsquo;approvisionnement en eau.<\/li>\n<li><strong>Ind\u00e9pendance :<\/strong> avec un syst\u00e8me de r\u00e9cup\u00e9ration d&rsquo;eau de pluie, vous \u00eates moins d\u00e9pendant de l&rsquo;approvisionnement en eau ext\u00e9rieur et vous disposez d&rsquo;une source d&rsquo;eau fiable pour vos besoins.<\/li>\n<li><strong>Protection de l&rsquo;environnement :<\/strong> en r\u00e9duisant la consommation d&rsquo;eau potable, vous contribuez \u00e0 la protection de l&rsquo;environnement, car moins d&rsquo;eau doit \u00eatre trait\u00e9e et transport\u00e9e.<\/li>\n<li><strong>Une meilleure qualit\u00e9 de l&rsquo;eau :<\/strong> l&rsquo;eau de pluie est plus douce que l&rsquo;eau potable et contient moins de min\u00e9raux. Cela permet \u00e9galement de prolonger la dur\u00e9e de vie de vos appareils \u00e9lectrom\u00e9nagers, car ils sont moins affect\u00e9s par les d\u00e9p\u00f4ts de calcaire et l&rsquo;encrassement.<\/li>\n<\/ol>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-97d9137\" data-id=\"97d9137\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d73a42f elementor-widget elementor-widget-text-editor\" data-id=\"d73a42f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"p1\"><span class=\"s1\" style=\"color: #95c03b;\">Comment fonctionne la r\u00e9cup\u00e9ration de l&rsquo;eau de pluie ?<\/span><\/h4>\n<p class=\"p1\"><span class=\"s1\">Lors de la r\u00e9cup\u00e9ration de l&rsquo;eau de pluie, l&rsquo;eau de pluie de votre toit est achemin\u00e9e via des goutti\u00e8res et des tuyaux de descente vers un r\u00e9servoir d&rsquo;eau de pluie sp\u00e9cial, souvent enterr\u00e9. Elle y est collect\u00e9e et stock\u00e9e. L&rsquo;eau collect\u00e9e est ensuite achemin\u00e9e \u00e0 l&rsquo;aide d&rsquo;une pompe vers les points d&rsquo;utilisation de la maison, o\u00f9 elle peut \u00eatre utilis\u00e9e \u00e0 diff\u00e9rentes fins.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4f518e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4f518e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3b7335\" data-id=\"a3b7335\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3328a50 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"3328a50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-water\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a34c44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a34c44\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65d4dc7\" data-id=\"65d4dc7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3672529 elementor-widget elementor-widget-text-editor\" data-id=\"3672529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Une installation de r\u00e9cup\u00e9ration d&rsquo;eau de pluie se compose g\u00e9n\u00e9ralement des \u00e9l\u00e9ments suivants :<\/strong><\/p>\n<ol>\n<li><strong>R\u00e9servoir d&rsquo;eau de pluie :<\/strong> l&rsquo;eau de pluie y est stock\u00e9e. Selon les besoins et la surface disponible, la citerne peut \u00eatre install\u00e9e en surface, sous terre ou une combinaison des deux variantes.<\/li>\n<li><strong>Syst\u00e8me de filtration :<\/strong> le syst\u00e8me de filtration veille \u00e0 ce que les grosses impuret\u00e9s comme les feuilles ou les particules de salet\u00e9 soient \u00e9limin\u00e9es de l&rsquo;eau de pluie avant qu&rsquo;elle n&rsquo;arrive dans le r\u00e9servoir.<\/li>\n<li><strong>Syst\u00e8me de pompage :<\/strong> une pompe achemine l&rsquo;eau de pluie collect\u00e9e vers les points d&rsquo;utilisation de la maison, comme les toilettes, les machines \u00e0 laver ou les syst\u00e8mes d&rsquo;arrosage du jardin.<\/li>\n<li><strong>Syst\u00e8me de r\u00e9alimentation :<\/strong> en cas de besoin, une r\u00e9alimentation automatique en eau potable peut \u00eatre effectu\u00e9e afin de s&rsquo;assurer qu&rsquo;il y a toujours suffisamment d&rsquo;eau.<\/li>\n<\/ol>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ae2c45f\" data-id=\"ae2c45f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2253df7 elementor-widget elementor-widget-text-editor\" data-id=\"2253df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #95c03b;\">Pourquoi demander \u00e0 ASKAL une installation de r\u00e9cup\u00e9ration d&rsquo;eau de pluie ?<\/span><\/h4>\n<p>Nous vous proposons une<\/p>\n<ul>\n<li><strong>un conseil professionnel :<\/strong> nous mettons nos connaissances techniques \u00e0 votre disposition et vous conseillons de mani\u00e8re approfondie sur les avantages et les possibilit\u00e9s de l&rsquo;utilisation de l&rsquo;eau de pluie.<\/li>\n<li><strong>Planification individuelle :<\/strong> chaque maison est unique, c&rsquo;est pourquoi nous d\u00e9veloppons des concepts sur mesure, parfaitement adapt\u00e9s \u00e0 vos besoins et aux conditions sur place.<\/li>\n<li><strong>Des produits de qualit\u00e9 :<\/strong> Nous travaillons avec des fabricants renomm\u00e9s pour vous proposer des composants de qualit\u00e9 et des installations de r\u00e9cup\u00e9ration d&rsquo;eau de pluie fiables.<\/li>\n<li><strong>Installation professionnelle :<\/strong> nos installateurs qualifi\u00e9s assurent une installation professionnelle et efficace de votre syst\u00e8me de r\u00e9cup\u00e9ration d&rsquo;eau de pluie.<\/li>\n<li><strong>Service apr\u00e8s-vente et maintenance :<\/strong> nous sommes \u00e9galement \u00e0 votre disposition apr\u00e8s l&rsquo;installation. Si vous avez des questions ou si vous avez besoin de maintenance, nos techniciens exp\u00e9riment\u00e9s sont \u00e0 votre disposition.<\/li>\n<\/ul>\n<p>Profitez des avantages de l&rsquo;installation de r\u00e9cup\u00e9ration d&rsquo;eau de pluie et prenez rendez-vous avec nous d\u00e8s aujourd&rsquo;hui pour un entretien conseil. Ensemble, nous trouverons la solution optimale pour rendre votre maison plus durable et plus respectueuse des ressources.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ba1d19 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ba1d19\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34b7ab6\" data-id=\"34b7ab6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98f2a1e elementor-widget elementor-widget-text-editor\" data-id=\"98f2a1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong><span class=\"--l --r sentence_highlight\">Vous \u00eates int\u00e9ress\u00e9(e) par un conseil ?<br \/><\/span><span class=\"--l --r sentence_highlight\">Alors, n&rsquo;h\u00e9sitez pas \u00e0 nous contacter !<\/span><\/strong><\/span><\/h3><p style=\"text-align: center;\"><span style=\"color: #000000;\">Veuillez noter que nous ne consultons pas nos e-mails en dehors des heures d&rsquo;ouverture.<\/span><br \/><span style=\"color: #000000;\">Si vous souhaitez <strong>joindre notre service d&rsquo;urgence<\/strong>, veuillez nous <strong>appeler au +352 72 92 55-1<\/strong> afin que nous puissions vous aider.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f98c01 elementor-widget elementor-widget-shortcode\" data-id=\"8f98c01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"frm_forms  with_frm_style frm_style_formidable-stil\" id=\"frm_form_6_container\" data-token=\"3dc677801b88236d4a6502a63428f4ca\">\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form \" id=\"form_kontakt-d2\" data-token=\"3dc677801b88236d4a6502a63428f4ca\">\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_screen_reader\">Contact FR<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"6\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_6\" id=\"frm_hide_fields_6\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"kontakt-d2\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_6\" name=\"frm_submit_entry_6\" value=\"ac8c0261e9\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/fr\/wp-json\/wp\/v2\/pages\/887\" \/><div id=\"frm_field_48_container\" class=\"frm_form_field form-field  frm_top_container frm3 frm_first\">\r\n\t<label for=\"field_bw38n2\" id=\"field_bw38n2_label\" class=\"frm_primary_label\">Civilit\u00e9\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t<input type=\"text\" id=\"field_bw38n2\" name=\"item_meta[48]\" value=\"\"  data-invmsg=\"Civilit\u00e9 ist ung\u00fcltig\" aria-invalid=\"false\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_49_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm9\">\r\n\t<div  id=\"field_rvxix2_label\" class=\"frm_primary_label\">Nom\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/div>\r\n\t<fieldset aria-labelledby=\"field_rvxix2_label\">\n\t<legend class=\"frm_screen_reader frm_hidden\">\n\t\tNom\t<\/legend>\n\n\t<div  class=\"frm_combo_inputs_container\" id=\"frm_combo_inputs_container_49\" data-name-layout=\"first_last\">\n\t\t\t\t\t<div\n\t\t\t\tid=\"frm_field_49-first_container\"\n\t\t\t\tclass=\"frm_form_field form-field frm_form_subfield-first  frm6\"\n\t\t\t\tdata-sub-field-name=\"first\"\n\t\t\t>\n\t\t\t\t<label for=\"field_rvxix2_first\" class=\"frm_screen_reader frm_hidden\">\n\t\t\t\t\tPr\u00e9nom\t\t\t\t<\/label>\n\n\t\t\t\t<input  type=\"text\" id=\"field_rvxix2_first\" value=\"\" name=\"item_meta[49][first]\" autocomplete=\"given-name\" data-reqmsg=\"Nom kann nicht leer sein.\" aria-required=\"true\" data-invmsg=\"Nom est non valide\" aria-invalid=\"false\"  \/><div class=\"frm_description\" id=\"frm_field_49_first_desc\">Pr\u00e9nom<\/div>\t\t\t<\/div>\n\t\t\t\t\t\t<div\n\t\t\t\tid=\"frm_field_49-last_container\"\n\t\t\t\tclass=\"frm_form_field form-field frm_form_subfield-last  frm6\"\n\t\t\t\tdata-sub-field-name=\"last\"\n\t\t\t>\n\t\t\t\t<label for=\"field_rvxix2_last\" class=\"frm_screen_reader frm_hidden\">\n\t\t\t\t\tNom\t\t\t\t<\/label>\n\n\t\t\t\t<input  type=\"text\" id=\"field_rvxix2_last\" value=\"\" name=\"item_meta[49][last]\" autocomplete=\"family-name\" data-reqmsg=\"Nom kann nicht leer sein.\" aria-required=\"true\" data-invmsg=\"Nom est non valide\" aria-invalid=\"false\"  \/><div class=\"frm_description\" id=\"frm_field_49_last_desc\">Nom<\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n<\/fieldset>\n\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_50_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first\">\r\n\t<label for=\"field_4yztc2\" id=\"field_4yztc2_label\" class=\"frm_primary_label\">E-Mail\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input type=\"email\" id=\"field_4yztc2\" name=\"item_meta[50]\" value=\"\"  data-reqmsg=\"E-Mail kann nicht leer sein.\" aria-required=\"true\" data-invmsg=\"E-Mail ist ung\u00fcltig\" aria-invalid=\"false\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_51_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6\">\r\n\t<label for=\"field_gjhtl2\" id=\"field_gjhtl2_label\" class=\"frm_primary_label\">T\u00e9l\u00e9phone\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input type=\"tel\" id=\"field_gjhtl2\" name=\"item_meta[51]\" value=\"\"  data-reqmsg=\"T\u00e9l\u00e9phone kann nicht leer sein.\" aria-required=\"true\" data-invmsg=\"T\u00e9l\u00e9phone ist ung\u00fcltig\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_52_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n\t<label for=\"field_e7l7b2\" id=\"field_e7l7b2_label\" class=\"frm_primary_label\">Rue & N\u00b0\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input type=\"text\" id=\"field_e7l7b2\" name=\"item_meta[52]\" value=\"\"  data-reqmsg=\"Rue &amp; N\u00b0 kann nicht leer sein.\" aria-required=\"true\" data-invmsg=\"Rue &amp; N\u00b0 ist ung\u00fcltig\" aria-invalid=\"false\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_53_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6 frm_first\">\r\n\t<label for=\"field_png2l2\" id=\"field_png2l2_label\" class=\"frm_primary_label\">B.P. & Ville\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input type=\"text\" id=\"field_png2l2\" name=\"item_meta[53]\" value=\"\"  data-reqmsg=\"B.P. &amp; Ville kann nicht leer sein.\" aria-required=\"true\" data-invmsg=\"B.P. &amp; Ville ist ung\u00fcltig\" aria-invalid=\"false\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_54_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm6\">\r\n\t<label for=\"field_teake2\" id=\"field_teake2_label\" class=\"frm_primary_label\">Pays\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[54]\" id=\"field_teake2\"  data-reqmsg=\"Pays kann nicht leer sein.\" aria-required=\"true\" data-invmsg=\"Pays ist ung\u00fcltig\" aria-invalid=\"false\"  >\n\t\t<option  value=\"Luxembourg\">Luxembourg<\/option><option  value=\"Allemagne\">Allemagne<\/option><option  value=\"France\">France<\/option><option  value=\"Belgique\">Belgique<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_55_container\" class=\"frm_form_field form-field  frm_top_container vertical_radio\">\r\n\t<div  id=\"field_9a7wp2_label\" class=\"frm_primary_label\">Je souhaite un\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/div>\r\n\t<div class=\"frm_opt_container\" aria-labelledby=\"field_9a7wp2_label\" role=\"group\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_55-0\">\t\t\t<label  for=\"field_9a7wp2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[55][]\" id=\"field_9a7wp2-0\" value=\"rappel\"  data-invmsg=\"Je souhaite un ist ung\u00fcltig\"   \/> rappel<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_55-1\">\t\t\t<label  for=\"field_9a7wp2-1\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[55][]\" id=\"field_9a7wp2-1\" value=\"rendez-vous\"  data-invmsg=\"Je souhaite un ist ung\u00fcltig\"   \/> rendez-vous<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_55-2\">\t\t\t<label  for=\"field_9a7wp2-2\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[55][]\" id=\"field_9a7wp2-2\" value=\"conseil\"  data-invmsg=\"Je souhaite un ist ung\u00fcltig\"   \/> conseil<\/label><\/div>\n<\/div>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_56_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n\t<label for=\"field_1a57\" id=\"field_1a57_label\" class=\"frm_primary_label\">Que pouvons-nous faire pour vous ?\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t<textarea name=\"item_meta[56]\" id=\"field_1a57\" rows=\"5\"  data-invmsg=\"Que pouvons-nous faire pour vous ? est non valide\" aria-invalid=\"false\"  ><\/textarea>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_57_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit frm_flex\">\r\n<button class=\"frm_button_submit\" type=\"submit\"  >Envoyer<\/button>\r\n\r\n\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_90_container\">\n\t\t\t<label for=\"field_lm0ym\" >\n\t\t\t\tSi vous \u00eates un humain, ne remplissez pas ce champ.\t\t\t<\/label>\n\t\t\t<input  id=\"field_lm0ym\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[90]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"PUG3EzpESolunKV1NPstieudhDiaRXcB2JQeUcnfQyk=\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cadeau de la nature R\u00e9cup\u00e9ration de l&rsquo;eau de pluie R\u00e9cup\u00e9ration de l&rsquo;eau de pluie : utilisez la force de la pluie pour votre m\u00e9nage ! L&rsquo;eau de pluie est une ressource pr\u00e9cieuse qui est souvent sous-estim\u00e9e. Une installation de r\u00e9cup\u00e9ration d&rsquo;eau de pluie vous permet d&rsquo;utiliser ce bien pr\u00e9cieux \u00e0 bon escient et de r\u00e9duire&hellip;&nbsp;<a href=\"https:\/\/askal.lu\/fr\/recuperation-de-leau-de-pluie\/\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">R\u00e9cup\u00e9ration de l&rsquo;eau de pluie<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-887","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/askal.lu\/fr\/wp-json\/wp\/v2\/pages\/887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/askal.lu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/askal.lu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/askal.lu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/askal.lu\/fr\/wp-json\/wp\/v2\/comments?post=887"}],"version-history":[{"count":18,"href":"https:\/\/askal.lu\/fr\/wp-json\/wp\/v2\/pages\/887\/revisions"}],"predecessor-version":[{"id":1868,"href":"https:\/\/askal.lu\/fr\/wp-json\/wp\/v2\/pages\/887\/revisions\/1868"}],"wp:attachment":[{"href":"https:\/\/askal.lu\/fr\/wp-json\/wp\/v2\/media?parent=887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}